{"id":13714,"date":"2019-07-11T05:49:13","date_gmt":"2019-07-11T05:49:13","guid":{"rendered":"http:\/\/www.edicionesalfar.es\/web-wordpress\/?post_type=product&#038;#022;p="},"modified":"2025-04-03T16:24:23","modified_gmt":"2025-04-03T14:24:23","slug":"violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento","status":"publish","type":"product","link":"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/","title":{"rendered":"VIOLENCIA, TELEVISI\u00d3N Y PUBLICIDAD. An\u00e1lisis narrativo de los espots publicitarios de contenido violento"},"content":{"rendered":"<p>VIOLENCIA, TELEVISI\u00d3N Y PUBLICIDAD. An\u00e1lisis narrativo de los espots publicitarios de contenido violento<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-size: 10pt;\"><span style=\"font-family: georgia,palatino;\">Obra que pretende cubrir la laguna investigadora sobre los contenidos violentos de la publicidad en televisi\u00f3n y que compara\u00a0dichos resultados con los obtenidos en otras investigaciones similares.<\/span><\/span><\/p>\n","protected":false},"featured_media":13715,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[376,591,22],"product_tag":[],"class_list":{"0":"post-13714","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-autores","7":"product_cat-garrido-lora-manuel","8":"product_cat-estudios-comunicacion","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIOLENCIA, TELEVISI\u00d3N Y PUBLICIDAD. An\u00e1lisis narrativo de los espots publicitarios de contenido violento - Ediciones Alfar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIOLENCIA, TELEVISI\u00d3N Y PUBLICIDAD. An\u00e1lisis narrativo de los espots publicitarios de contenido violento - Ediciones Alfar\" \/>\n<meta property=\"og:description\" content=\"Obra que pretende cubrir la laguna investigadora sobre los contenidos violentos de la publicidad en televisi\u00f3n y que compara\u00a0dichos resultados con los obtenidos en otras investigaciones similares.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/\" \/>\n<meta property=\"og:site_name\" content=\"Ediciones Alfar\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-03T14:24:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2019\/05\/violencia.jpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/producto\\\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\\\/\",\"url\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/producto\\\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\\\/\",\"name\":\"VIOLENCIA, TELEVISI\u00d3N Y PUBLICIDAD. An\u00e1lisis narrativo de los espots publicitarios de contenido violento - Ediciones Alfar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/producto\\\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/producto\\\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/violencia.jpg.jpg\",\"datePublished\":\"2019-07-11T05:49:13+00:00\",\"dateModified\":\"2025-04-03T14:24:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/producto\\\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/producto\\\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/producto\\\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/violencia.jpg.jpg\",\"contentUrl\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/violencia.jpg.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/producto\\\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e1logo\",\"item\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/catalogo\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"VIOLENCIA, TELEVISI\u00d3N Y PUBLICIDAD. An\u00e1lisis narrativo de los espots publicitarios de contenido violento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/\",\"name\":\"Ediciones Alfar\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIOLENCIA, TELEVISI\u00d3N Y PUBLICIDAD. An\u00e1lisis narrativo de los espots publicitarios de contenido violento - Ediciones Alfar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/","og_locale":"es_ES","og_type":"article","og_title":"VIOLENCIA, TELEVISI\u00d3N Y PUBLICIDAD. An\u00e1lisis narrativo de los espots publicitarios de contenido violento - Ediciones Alfar","og_description":"Obra que pretende cubrir la laguna investigadora sobre los contenidos violentos de la publicidad en televisi\u00f3n y que compara\u00a0dichos resultados con los obtenidos en otras investigaciones similares.","og_url":"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/","og_site_name":"Ediciones Alfar","article_modified_time":"2025-04-03T14:24:23+00:00","og_image":[{"url":"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2019\/05\/violencia.jpg.jpg","width":1,"height":1,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/","url":"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/","name":"VIOLENCIA, TELEVISI\u00d3N Y PUBLICIDAD. An\u00e1lisis narrativo de los espots publicitarios de contenido violento - Ediciones Alfar","isPartOf":{"@id":"https:\/\/edicionesalfar.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/#primaryimage"},"image":{"@id":"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/#primaryimage"},"thumbnailUrl":"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2019\/05\/violencia.jpg.jpg","datePublished":"2019-07-11T05:49:13+00:00","dateModified":"2025-04-03T14:24:23+00:00","breadcrumb":{"@id":"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/#primaryimage","url":"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2019\/05\/violencia.jpg.jpg","contentUrl":"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2019\/05\/violencia.jpg.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/edicionesalfar.es\/es\/producto\/violencia-television-y-publicidad-analisis-narrativo-de-los-espots-publicitarios-de-contenido-violento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/edicionesalfar.es\/es\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e1logo","item":"https:\/\/edicionesalfar.es\/es\/catalogo\/"},{"@type":"ListItem","position":3,"name":"VIOLENCIA, TELEVISI\u00d3N Y PUBLICIDAD. An\u00e1lisis narrativo de los espots publicitarios de contenido violento"}]},{"@type":"WebSite","@id":"https:\/\/edicionesalfar.es\/es\/#website","url":"https:\/\/edicionesalfar.es\/es\/","name":"Ediciones Alfar","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/edicionesalfar.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/product\/13714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/comments?post=13714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/media\/13715"}],"wp:attachment":[{"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/media?parent=13714"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/product_brand?post=13714"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/product_cat?post=13714"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/product_tag?post=13714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}