{"id":119654,"date":"2023-02-20T14:29:01","date_gmt":"2023-02-20T13:29:01","guid":{"rendered":"https:\/\/edicionesalfar.es\/es\/?p=119654"},"modified":"2023-02-20T14:29:01","modified_gmt":"2023-02-20T13:29:01","slug":"diario-de-sevilla-la-razon-de-la-sinrazon","status":"publish","type":"post","link":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/","title":{"rendered":"Diario de Sevilla &#8211; La Raz\u00f3n de la Sinraz\u00f3n"},"content":{"rendered":"<h1 class=\"pg-bkn-headline\">El Gald\u00f3s m\u00e1s regeneracionista<\/h1>\n<ul class=\"summary\">\n<li class=\"summary-entry fa-i\">La editorial sevillana Alfar publica una edici\u00f3n cr\u00edtica de &#8216;La raz\u00f3n de la sinraz\u00f3n&#8217;, obra en la que el autor de los &#8216;Episodios nacionales&#8217; retrata, a trav\u00e9s de arquetipos, la coyuntura de Espa\u00f1a en la Restauraci\u00f3n<\/li>\n<\/ul>\n<p>https:\/\/www.diariodesevilla.es\/ocio\/Galdos-regeneracionista_0_1767125226.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gald\u00f3s m\u00e1s regeneracionista La editorial sevillana Alfar publica una edici\u00f3n cr\u00edtica de &#8216;La raz\u00f3n de la sinraz\u00f3n&#8217;, obra en la que el autor de los &#8216;Episodios nacionales&#8217; retrata, a trav\u00e9s de arquetipos, la coyuntura de Espa\u00f1a en la Restauraci\u00f3n https:\/\/www.diariodesevilla.es\/ocio\/Galdos-regeneracionista_0_1767125226.html<\/p>\n","protected":false},"author":2,"featured_media":119655,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-119654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diario de Sevilla - La Raz\u00f3n de la Sinraz\u00f3n - Ediciones Alfar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diario de Sevilla - La Raz\u00f3n de la Sinraz\u00f3n - Ediciones Alfar\" \/>\n<meta property=\"og:description\" content=\"El Gald\u00f3s m\u00e1s regeneracionista La editorial sevillana Alfar publica una edici\u00f3n cr\u00edtica de &#8216;La raz\u00f3n de la sinraz\u00f3n&#8217;, obra en la que el autor de los &#8216;Episodios nacionales&#8217; retrata, a trav\u00e9s de arquetipos, la coyuntura de Espa\u00f1a en la Restauraci\u00f3n https:\/\/www.diariodesevilla.es\/ocio\/Galdos-regeneracionista_0_1767125226.html\" \/>\n<meta property=\"og:url\" content=\"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/\" \/>\n<meta property=\"og:site_name\" content=\"Ediciones Alfar\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-20T13:29:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2023\/02\/Sin-titulo-1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1327\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ediciones Alfar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ediciones Alfar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/\"},\"author\":{\"name\":\"Ediciones Alfar\",\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/#\\\/schema\\\/person\\\/1b0c6858b4bf43756e6f4cdb097d7a87\"},\"headline\":\"Diario de Sevilla &#8211; La Raz\u00f3n de la Sinraz\u00f3n\",\"datePublished\":\"2023-02-20T13:29:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/\"},\"wordCount\":67,\"image\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Sin-titulo-1-2.jpg\",\"articleSection\":[\"NOTICIAS Y EVENTOS\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/\",\"url\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/\",\"name\":\"Diario de Sevilla - La Raz\u00f3n de la Sinraz\u00f3n - Ediciones Alfar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Sin-titulo-1-2.jpg\",\"datePublished\":\"2023-02-20T13:29:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/#\\\/schema\\\/person\\\/1b0c6858b4bf43756e6f4cdb097d7a87\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Sin-titulo-1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Sin-titulo-1-2.jpg\",\"width\":1327,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/2023\\\/02\\\/20\\\/diario-de-sevilla-la-razon-de-la-sinrazon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diario de Sevilla &#8211; La Raz\u00f3n de la Sinraz\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/\",\"name\":\"Ediciones Alfar\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/#\\\/schema\\\/person\\\/1b0c6858b4bf43756e6f4cdb097d7a87\",\"name\":\"Ediciones Alfar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1670c9e9499353f5e7e1591395d4bbd72211f3945d052f1f5b166b3d2a0286f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1670c9e9499353f5e7e1591395d4bbd72211f3945d052f1f5b166b3d2a0286f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1670c9e9499353f5e7e1591395d4bbd72211f3945d052f1f5b166b3d2a0286f2?s=96&d=mm&r=g\",\"caption\":\"Ediciones Alfar\"},\"url\":\"https:\\\/\\\/edicionesalfar.es\\\/es\\\/author\\\/alfar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diario de Sevilla - La Raz\u00f3n de la Sinraz\u00f3n - Ediciones Alfar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/","og_locale":"es_ES","og_type":"article","og_title":"Diario de Sevilla - La Raz\u00f3n de la Sinraz\u00f3n - Ediciones Alfar","og_description":"El Gald\u00f3s m\u00e1s regeneracionista La editorial sevillana Alfar publica una edici\u00f3n cr\u00edtica de &#8216;La raz\u00f3n de la sinraz\u00f3n&#8217;, obra en la que el autor de los &#8216;Episodios nacionales&#8217; retrata, a trav\u00e9s de arquetipos, la coyuntura de Espa\u00f1a en la Restauraci\u00f3n https:\/\/www.diariodesevilla.es\/ocio\/Galdos-regeneracionista_0_1767125226.html","og_url":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/","og_site_name":"Ediciones Alfar","article_published_time":"2023-02-20T13:29:01+00:00","og_image":[{"width":1327,"height":850,"url":"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2023\/02\/Sin-titulo-1-2.jpg","type":"image\/jpeg"}],"author":"Ediciones Alfar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ediciones Alfar","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/#article","isPartOf":{"@id":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/"},"author":{"name":"Ediciones Alfar","@id":"https:\/\/edicionesalfar.es\/es\/#\/schema\/person\/1b0c6858b4bf43756e6f4cdb097d7a87"},"headline":"Diario de Sevilla &#8211; La Raz\u00f3n de la Sinraz\u00f3n","datePublished":"2023-02-20T13:29:01+00:00","mainEntityOfPage":{"@id":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/"},"wordCount":67,"image":{"@id":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/#primaryimage"},"thumbnailUrl":"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2023\/02\/Sin-titulo-1-2.jpg","articleSection":["NOTICIAS Y EVENTOS"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/","url":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/","name":"Diario de Sevilla - La Raz\u00f3n de la Sinraz\u00f3n - Ediciones Alfar","isPartOf":{"@id":"https:\/\/edicionesalfar.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/#primaryimage"},"image":{"@id":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/#primaryimage"},"thumbnailUrl":"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2023\/02\/Sin-titulo-1-2.jpg","datePublished":"2023-02-20T13:29:01+00:00","author":{"@id":"https:\/\/edicionesalfar.es\/es\/#\/schema\/person\/1b0c6858b4bf43756e6f4cdb097d7a87"},"breadcrumb":{"@id":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/#primaryimage","url":"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2023\/02\/Sin-titulo-1-2.jpg","contentUrl":"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2023\/02\/Sin-titulo-1-2.jpg","width":1327,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/edicionesalfar.es\/es\/2023\/02\/20\/diario-de-sevilla-la-razon-de-la-sinrazon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/edicionesalfar.es\/es\/"},{"@type":"ListItem","position":2,"name":"Diario de Sevilla &#8211; La Raz\u00f3n de la Sinraz\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/edicionesalfar.es\/es\/#website","url":"https:\/\/edicionesalfar.es\/es\/","name":"Ediciones Alfar","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/edicionesalfar.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/edicionesalfar.es\/es\/#\/schema\/person\/1b0c6858b4bf43756e6f4cdb097d7a87","name":"Ediciones Alfar","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1670c9e9499353f5e7e1591395d4bbd72211f3945d052f1f5b166b3d2a0286f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1670c9e9499353f5e7e1591395d4bbd72211f3945d052f1f5b166b3d2a0286f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1670c9e9499353f5e7e1591395d4bbd72211f3945d052f1f5b166b3d2a0286f2?s=96&d=mm&r=g","caption":"Ediciones Alfar"},"url":"https:\/\/edicionesalfar.es\/es\/author\/alfar\/"}]}},"jetpack_featured_media_url":"https:\/\/edicionesalfar.es\/es\/wp-content\/uploads\/2023\/02\/Sin-titulo-1-2.jpg","_links":{"self":[{"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/posts\/119654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/comments?post=119654"}],"version-history":[{"count":1,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/posts\/119654\/revisions"}],"predecessor-version":[{"id":119656,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/posts\/119654\/revisions\/119656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/media\/119655"}],"wp:attachment":[{"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/media?parent=119654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/categories?post=119654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edicionesalfar.es\/es\/wp-json\/wp\/v2\/tags?post=119654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}